{"id":12494,"date":"2021-06-10T08:53:58","date_gmt":"2021-06-10T06:53:58","guid":{"rendered":"https:\/\/skrivanek.cz\/?page_id=12494"},"modified":"2025-11-24T13:21:37","modified_gmt":"2025-11-24T12:21:37","slug":"poptavka","status":"publish","type":"page","link":"https:\/\/skrivanek.cz\/cz\/poptavka\/","title":{"rendered":"Popt\u00e1vka"},"content":{"rendered":"<div id=\"pl-12494\"  class=\"panel-layout\" ><div id=\"pg-12494-0\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-padding-none panel-row-style panel-row-style-for-12494-0\" ><div id=\"pgc-12494-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-12494-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 class=\"page-title border-bottom-c-default\">Jak v\u00e1m m\u016f\u017eeme pomoci?<\/h2>\n<\/div>\n<\/div><\/div><div id=\"panel-12494-0-0-1\" class=\"so-panel widget widget_wpforms-widget wpforms-widget panel-last-child\" data-index=\"1\" >\r\n<style type=\"text\/css\">\r\n\r\n\r\n\r\nbody #wpforms-75185 {\r\n\t\t\r\n\t\t\tfont-family:inherit;}\r\n\r\n\t\r\n\r\n\tbody #wpforms-75185 .wpforms-head-container {\r\n\t\tborder-width: 0px;}\r\n\r\n\tbody #wpforms-75185 .wpforms-head-container .wpforms-title {\r\n\t\t}\r\n\r\n\tbody #wpforms-75185 .wpforms-head-container .wpforms-description {\r\n\t\t\t\tdisplay:block;\r\n\t}\r\n\r\n\r\n\tbody #wpforms-75185 .wpforms-submit-container .wpforms-submit, body #wpforms-75185 .wpforms-field-pagebreak button.wpforms-page-button {\r\n\t\tcolor:#ffffff ;background-color:#ff643b ;border-width:0px ;border-style:solid ;border-radius:10px ;-web-border-radius:10px ;-moz-border-radius:10px ;\t\t\t}\r\n\r\n\tbody #wpforms-75185 .wpforms-submit-container .wpforms-submit:hover, body #wpforms-75185 .wpforms-field-pagebreak button.wpforms-page-button:hover {\r\n\tbackground-color:;\tcolor:;\t}\r\n\r\n\tbody #wpforms-75185 .wpforms-submit-container,\r\n\tbody #wpforms-75185 .wpforms-field-pagebreak .wpforms-pagebreak-left{\r\n\t\t}\r\n\r\n\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field input[type=text],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field input[type=email],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field input[type=tel],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field input[type=url],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field input[type=password],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field input[type=number]\r\n\t{\r\n\t\tborder-width:1px ;border-style:solid ;\t\t\t}\r\n\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field .wpforms-field-row\r\n\t{\r\n\t\t\t}\r\n\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-layout.wpforms-field input[type=text],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-layout.wpforms-field input[type=email],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-layout.wpforms-field input[type=tel],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-layout.wpforms-field input[type=url],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-layout.wpforms-field input[type=password],\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-layout.wpforms-field input[type=number]{\r\n\t\twidth: 100%;\r\n\t}\r\n\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field .wpforms-field-row input[type=text]{\r\n\t\twidth: 100%;\r\n\t}\r\n\r\n\r\n\r\n\t#wpforms-75185 .wpforms-form .wpforms-field-layout-rows,\r\n\t#wpforms-75185 .wpforms-form .wpforms-field-layout-columns{\r\n\t\t\t}\r\n\r\n\r\n\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field textarea {\r\n\t\t\t\t\tborder-width: 1px;\t}\r\n\r\n \r\n\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field select {\r\n\r\n\t\t\r\n\t\tborder-width: 1px;\t}\r\n\r\n\t\/* dropdown styles on modern background *\/\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-select-style-modern .choices__inner{\r\n\t\t\t\t\r\n\t}\r\n\r\n\t\/* background color on modern dropdown *\/\r\n\t\r\n \r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-radio li label,\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-payment-multiple li label {\r\n\t\t\t}\r\n \r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field-checkbox li label {\r\n\t\t\t}\r\n \r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field .wpforms-field-description {\r\n\r\n\t\t\t}\r\n\r\n \r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field label.wpforms-field-label,\r\n\tbody #wpforms-75185 .wpforms-form .wpforms-field .wpforms-field-label {\r\n\t\tfont-weight: bold;\t}\r\n\r\n\r\n \r\n\tbody #wpforms-confirmation-75185  {\r\n\r\n\t\t\t\tborder-width: 1px;\t}\r\n\r\n\tbody #wpforms-confirmation-75185 p{\r\n\t\ttext-transform: uppercase;\r\n\t\ttext-decoration: underline;\r\n\t\tcolor: inherit;\r\n\t}\r\n\r\n \r\n\tbody #wpforms-75185 label.wpforms-error,\r\n\tbody #wpforms-75185 .wpforms-error[role=\"alert\"] {\r\n\t\t\r\n\t\t\t\tborder-width: 1px;\t}\r\n\/* Styling for Tablets *\/\r\n@media only screen and (max-width: 800px) and (min-width:481px) {\r\n\t\r\n\r\n\r\n\r\n}\r\n\r\n@media only screen and (max-width: 480px){\r\n\t\r\n\r\n\r\n\r\n}\r\n\/*Option to add custom CSS *\/\r\n\r\n\r\n\r\n\t\t<\/style>\r\n\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-75185\"><form id=\"wpforms-form-75185\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"75185\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/cz\/wp-json\/wp\/v2\/pages\/12494?wpforms_form_id=75185\" data-token=\"20b5273121826cdf041b1eb5850ebe75\" data-token-time=\"1778683328\"><noscript class=\"wpforms-error-noscript\">Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v&nbsp;prohl\u00ed\u017ee\u010di JavaScript.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v&nbsp;prohl\u00ed\u017ee\u010di JavaScript.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-75185-field_10-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline wpforms-conditional-trigger\" data-field-id=\"10\"><fieldset><legend class=\"wpforms-field-label\">Objedn\u00e1v\u00e1m <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-75185-field_10\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_10_1\" name=\"wpforms[fields][10]\" value=\"jako fyzick\u00e1 osoba\" aria-errormessage=\"wpforms-75185-field_10_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_10_1\">jako fyzick\u00e1 osoba<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_10_2\" name=\"wpforms[fields][10]\" value=\"pro firmu\" aria-errormessage=\"wpforms-75185-field_10_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_10_2\">pro firmu<\/label><\/li><\/ul><\/fieldset><\/div>\t\t<div id=\"wpforms-75185-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-75185-field_4\" >Typ lektora Preference<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-75185-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-75185-field_31-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-2-columns wpforms-conditional-trigger\" data-field-id=\"31\"><fieldset><legend class=\"wpforms-field-label\">O jakou slu\u017ebu m\u00e1te z\u00e1jem? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-75185-field_31\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_31_1\" name=\"wpforms[fields][31]\" value=\"p\u0159eklady\" aria-errormessage=\"wpforms-75185-field_31_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_31_1\">p\u0159eklady<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_31_2\" name=\"wpforms[fields][31]\" value=\"tlumo\u010den\u00ed\" aria-errormessage=\"wpforms-75185-field_31_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_31_2\">tlumo\u010den\u00ed<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_31_3\" name=\"wpforms[fields][31]\" value=\"jazykov\u00e1 v\u00fduka\" aria-errormessage=\"wpforms-75185-field_31_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_31_3\">jazykov\u00e1 v\u00fduka<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_31_4\" name=\"wpforms[fields][31]\" value=\"AI\" aria-errormessage=\"wpforms-75185-field_31_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_31_4\">AI<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_17-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"17\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_17\">Jazykov\u00e1 kombinace<\/label><input type=\"text\" id=\"wpforms-75185-field_17\" class=\"wpforms-field-medium\" name=\"wpforms[fields][17]\" aria-errormessage=\"wpforms-75185-field_17-error\" aria-describedby=\"wpforms-75185-field_17-description\" ><div id=\"wpforms-75185-field_17-description\" class=\"wpforms-field-description\">nap\u0159. \u010de\u0161tina - angli\u010dtina<\/div><\/div><div id=\"wpforms-75185-field_18-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"18\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">\u00da\u010del p\u0159ekladu <\/legend><ul id=\"wpforms-75185-field_18\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_18_1\" name=\"wpforms[fields][18]\" value=\"P\u0159eklad informativn\u00ed\" aria-errormessage=\"wpforms-75185-field_18_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_18_1\">P\u0159eklad informativn\u00ed<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_18_2\" name=\"wpforms[fields][18]\" value=\"Soudn\u00ed p\u0159eklad s ov\u011b\u0159en\u00edm\" aria-errormessage=\"wpforms-75185-field_18_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_18_2\">Soudn\u00ed p\u0159eklad s&nbsp;ov\u011b\u0159en\u00edm<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_18_3\" name=\"wpforms[fields][18]\" value=\"Elektronick\u00fd soudn\u00ed p\u0159eklad s ov\u011b\u0159en\u00edm\" aria-errormessage=\"wpforms-75185-field_18_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_18_3\">Elektronick\u00fd soudn\u00ed p\u0159eklad s&nbsp;ov\u011b\u0159en\u00edm<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_18_4\" name=\"wpforms[fields][18]\" value=\"Zve\u0159ejn\u011bn\u00ed na webov\u00fdch str\u00e1nk\u00e1ch\" aria-errormessage=\"wpforms-75185-field_18_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_18_4\">Zve\u0159ejn\u011bn\u00ed na webov\u00fdch str\u00e1nk\u00e1ch<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_18_5\" name=\"wpforms[fields][18]\" value=\"P\u0159eklad do tisku a ve\u0159ejn\u00e9ho \u0161\u00ed\u0159en\u00ed\" aria-errormessage=\"wpforms-75185-field_18_5-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_18_5\">P\u0159eklad do tisku a&nbsp;ve\u0159ejn\u00e9ho \u0161\u00ed\u0159en\u00ed<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_18_6\" name=\"wpforms[fields][18]\" value=\"P\u0159eklad pro osobn\u00ed vyu\u017eit\u00ed\" aria-errormessage=\"wpforms-75185-field_18_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_18_6\">P\u0159eklad pro osobn\u00ed vyu\u017eit\u00ed<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_23-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"23\" style=\"display:none;\"><div id=\"wpforms-75185-field_23\" aria-errormessage=\"wpforms-75185-field_23-error\"><span style=\"color: #FF643B; font-size:20px\"><strong>Vyhotoven\u00fd elektronick\u00fd soudn\u00ed p\u0159eklad s&nbsp;ov\u011b\u0159en\u00edm bude zasl\u00e1n na V\u00e1\u0161 e-mail. <\/strong><\/span><\/div><\/div><div id=\"wpforms-75185-field_20-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_20\">O\u010dek\u00e1van\u00fd term\u00edn vyhotoven\u00ed<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-75185-field_20\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"1\" data-disable-todays-date=\"1\" data-input=\"true\" name=\"wpforms[fields][20][date]\" aria-errormessage=\"wpforms-75185-field_20-error\" ><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-75185-field_21-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-show wpforms-field-select-style-classic\" data-field-id=\"21\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_21\">Vyberte pobo\u010dku, kde si p\u0159eklad vyzvednete<\/label><select id=\"wpforms-75185-field_21\" class=\"wpforms-field-medium\" name=\"wpforms[fields][21]\"><option value=\"Praha\"  class=\"choice-1 depth-1\"  >Praha<\/option><option value=\"Brno\"  class=\"choice-2 depth-1\"  >Brno<\/option><option value=\"Ostrava\"  class=\"choice-3 depth-1\"  >Ostrava<\/option><option value=\"Plze\u0148\"  class=\"choice-4 depth-1\"  >Plze\u0148<\/option><option value=\"Liberec\"  class=\"choice-5 depth-1\"  >Liberec<\/option><option value=\"\u010cesk\u00e9 Bud\u011bjovice\"  class=\"choice-6 depth-1\"  >\u010cesk\u00e9 Bud\u011bjovice<\/option><option value=\"Hradec Kr\u00e1lov\u00e9\"  class=\"choice-7 depth-1\"  >Hradec Kr\u00e1lov\u00e9<\/option><option value=\"Pardubice\"  class=\"choice-8 depth-1\"  >Pardubice<\/option><option value=\"\u00dast\u00ed nad Labem\"  class=\"choice-9 depth-1\"  >\u00dast\u00ed nad Labem<\/option><option value=\"Zl\u00edn\"  class=\"choice-10 depth-1\"  >Zl\u00edn<\/option><\/select><\/div><div id=\"wpforms-75185-field_24-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"24\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Typ akce \/ tlumo\u010den\u00ed<\/legend><ul id=\"wpforms-75185-field_24\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_24_1\" name=\"wpforms[fields][24]\" value=\"Obchodn\u00ed sch\u016fzka\" aria-errormessage=\"wpforms-75185-field_24_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_24_1\">Obchodn\u00ed sch\u016fzka<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_24_2\" name=\"wpforms[fields][24]\" value=\"Konference\" aria-errormessage=\"wpforms-75185-field_24_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_24_2\">Konference<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_24_3\" name=\"wpforms[fields][24]\" value=\"\u0160kolen\u00ed \/ p\u0159edn\u00e1\u0161ka\" aria-errormessage=\"wpforms-75185-field_24_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_24_3\">\u0160kolen\u00ed \/ p\u0159edn\u00e1\u0161ka<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_24_4\" name=\"wpforms[fields][24]\" value=\"Tlumo\u010den\u00ed ve v\u00fdrob\u011b \/ provozu\" aria-errormessage=\"wpforms-75185-field_24_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_24_4\">Tlumo\u010den\u00ed ve v\u00fdrob\u011b \/ provozu<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_24_5\" name=\"wpforms[fields][24]\" value=\"\u00da\u0159edn\u00ed jedn\u00e1n\u00ed \/ soudn\u00ed tlumo\u010den\u00ed\" aria-errormessage=\"wpforms-75185-field_24_5-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_24_5\">\u00da\u0159edn\u00ed jedn\u00e1n\u00ed \/ soudn\u00ed tlumo\u010den\u00ed<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_24_6\" name=\"wpforms[fields][24]\" value=\"Jin\u00e9\" aria-errormessage=\"wpforms-75185-field_24_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_24_6\">Jin\u00e9<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_25-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"25\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_25\">Term\u00edn tlumo\u010den\u00ed<\/label><input type=\"text\" id=\"wpforms-75185-field_25\" class=\"wpforms-field-medium\" name=\"wpforms[fields][25]\" aria-errormessage=\"wpforms-75185-field_25-error\" ><\/div><div id=\"wpforms-75185-field_26-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"26\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Jak\u00fd jazyk budeme vyu\u010dovat?<\/legend><ul id=\"wpforms-75185-field_26\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_1\" name=\"wpforms[fields][26]\" value=\"angli\u010dtina\" aria-errormessage=\"wpforms-75185-field_26_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_1\">angli\u010dtina<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_2\" name=\"wpforms[fields][26]\" value=\"n\u011bm\u010dina\" aria-errormessage=\"wpforms-75185-field_26_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_2\">n\u011bm\u010dina<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_3\" name=\"wpforms[fields][26]\" value=\"francouz\u0161tina\" aria-errormessage=\"wpforms-75185-field_26_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_3\">francouz\u0161tina<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_4\" name=\"wpforms[fields][26]\" value=\"ital\u0161tina\" aria-errormessage=\"wpforms-75185-field_26_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_4\">ital\u0161tina<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_5\" name=\"wpforms[fields][26]\" value=\"ru\u0161tina\" aria-errormessage=\"wpforms-75185-field_26_5-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_5\">ru\u0161tina<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_6\" name=\"wpforms[fields][26]\" value=\"\u0161pan\u011bl\u0161tina\" aria-errormessage=\"wpforms-75185-field_26_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_6\">\u0161pan\u011bl\u0161tina<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_7\" name=\"wpforms[fields][26]\" value=\"\u010de\u0161tina pro cizince\" aria-errormessage=\"wpforms-75185-field_26_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_7\">\u010de\u0161tina pro cizince<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_26_8\" name=\"wpforms[fields][26]\" value=\"jin\u00fd\" aria-errormessage=\"wpforms-75185-field_26_8-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_26_8\">jin\u00fd<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_27-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"27\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Jak\u00e9 je va\u0161e jazykov\u00e1 \u00farove\u0148?<\/legend><ul id=\"wpforms-75185-field_27\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_1\" name=\"wpforms[fields][27]\" value=\"A1 za\u010d\u00e1te\u010dn\u00edk\" aria-errormessage=\"wpforms-75185-field_27_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_1\">A1 za\u010d\u00e1te\u010dn\u00edk<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_2\" name=\"wpforms[fields][27]\" value=\"A2 m\u00edrn\u011b pokro\u010dil\u00fd\" aria-errormessage=\"wpforms-75185-field_27_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_2\">A2 m\u00edrn\u011b pokro\u010dil\u00fd<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_3\" name=\"wpforms[fields][27]\" value=\"B1 st\u0159edn\u011b pokro\u010dil\u00fd\" aria-errormessage=\"wpforms-75185-field_27_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_3\">B1 st\u0159edn\u011b pokro\u010dil\u00fd<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_4\" name=\"wpforms[fields][27]\" value=\"B2 pokro\u010dil\u00fd\" aria-errormessage=\"wpforms-75185-field_27_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_4\">B2 pokro\u010dil\u00fd<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_5\" name=\"wpforms[fields][27]\" value=\"C1 velmi pokro\u010dil\u00fd\" aria-errormessage=\"wpforms-75185-field_27_5-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_5\">C1 velmi pokro\u010dil\u00fd<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_6\" name=\"wpforms[fields][27]\" value=\"C2 expert\" aria-errormessage=\"wpforms-75185-field_27_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_6\">C2 expert<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_27_7\" name=\"wpforms[fields][27]\" value=\"nev\u00edm\" aria-errormessage=\"wpforms-75185-field_27_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_27_7\">nev\u00edm<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_28-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"28\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Forma v\u00fduky<\/legend><ul id=\"wpforms-75185-field_28\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_28_1\" name=\"wpforms[fields][28]\" value=\"online\" aria-errormessage=\"wpforms-75185-field_28_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_28_1\">online<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_28_2\" name=\"wpforms[fields][28]\" value=\"prezen\u010dn\u011b v u\u010debn\u011b J\u0160 Sk\u0159iv\u00e1nek\" aria-errormessage=\"wpforms-75185-field_28_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_28_2\">prezen\u010dn\u011b v&nbsp;u\u010debn\u011b J\u0160 Sk\u0159iv\u00e1nek<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_28_3\" name=\"wpforms[fields][28]\" value=\"jinde\" aria-errormessage=\"wpforms-75185-field_28_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_28_3\">jinde<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_29-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"29\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Preference lektora<\/legend><ul id=\"wpforms-75185-field_29\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_29_1\" name=\"wpforms[fields][29]\" value=\"\u010desk\u00fd lektor\" aria-errormessage=\"wpforms-75185-field_29_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_29_1\">\u010desk\u00fd lektor<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_29_2\" name=\"wpforms[fields][29]\" value=\"rodil\u00fd mluv\u010d\u00ed\" aria-errormessage=\"wpforms-75185-field_29_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_29_2\">rodil\u00fd mluv\u010d\u00ed<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_29_3\" name=\"wpforms[fields][29]\" value=\"nev\u00edm \/ nem\u00e1m preferenci\" aria-errormessage=\"wpforms-75185-field_29_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_29_3\">nev\u00edm \/ nem\u00e1m preferenci<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_30-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"30\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Vyberte si bal\u00ed\u010dek v\u00fduky<\/legend><ul id=\"wpforms-75185-field_30\"><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_30_2\" name=\"wpforms[fields][30]\" value=\"10\u00d7 60 minut\" aria-errormessage=\"wpforms-75185-field_30_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_30_2\">10\u00d7 60 minut<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_30_3\" name=\"wpforms[fields][30]\" value=\"15\u00d7 60 minut\" aria-errormessage=\"wpforms-75185-field_30_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_30_3\">15\u00d7 60 minut<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_30_4\" name=\"wpforms[fields][30]\" value=\"20\u00d7 60 minut\" aria-errormessage=\"wpforms-75185-field_30_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_30_4\">20\u00d7 60 minut<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_30_6\" name=\"wpforms[fields][30]\" value=\"10\u00d7 90 minut\" aria-errormessage=\"wpforms-75185-field_30_6-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_30_6\">10\u00d7 90 minut<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_30_7\" name=\"wpforms[fields][30]\" value=\"15\u00d7 90 minut\" aria-errormessage=\"wpforms-75185-field_30_7-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_30_7\">15\u00d7 90 minut<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"radio\" id=\"wpforms-75185-field_30_8\" name=\"wpforms[fields][30]\" value=\"20\u00d7 90 minut\" aria-errormessage=\"wpforms-75185-field_30_8-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75185-field_30_8\">20\u00d7 90 minut<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75185-field_22-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"22\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75185-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_7\">Chcete doplnit n\u011bjak\u00e9 informace?<\/label><textarea id=\"wpforms-75185-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-75185-field_7-error\" aria-describedby=\"wpforms-75185-field_7-description\" ><\/textarea><div id=\"wpforms-75185-field_7-description\" class=\"wpforms-field-description\">Jak v\u00e1m m\u016f\u017eeme pomoci? Dejte n\u00e1m v\u011bd\u011bt, co aktu\u00e1ln\u011b \u0159e\u0161\u00edte. M\u00e1te na n\u00e1s ot\u00e1zku? Jsme tu pro v\u00e1s.<\/div><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75185-field_13-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_13\">Nahr\u00e1n\u00ed souboru<\/label><div\n\t\tclass=\"wpforms-uploader \"\n\t\tdata-field-id=\"13\"\n\t\tdata-form-id=\"75185\"\n\t\tdata-input-name=\"wpforms_75185_13\"\n\t\tdata-extensions=\"txt,rtf,odf,pdf,doc,docx,ppt,pptx,xls,xlsx,zip\"\n\t\tdata-max-size=\"33554432\"\n\t\tdata-max-file-number=\"10\"\n\t\tdata-post-max-size=\"33554432\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">M\u016f\u017eete nahr\u00e1t a\u017e 10 soubor\u016f.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-75185-field_13\"\n\t\tname=\"wpforms_75185_13\" \t\tvalue=\"\">\n<div id=\"wpforms-75185-field_13-description\" class=\"wpforms-field-description\"> <font color=\"#FF643B\" size=\"3\"><b>Ochrana va\u0161ich dokument\u016f je pro n\u00e1s prioritou. Va\u0161e soubory jsou u&nbsp;n\u00e1s v&nbsp;bezpe\u010d\u00ed.<\/b><\/font>\nTypy soubor\u016f: txt, rtf, odf, pdf, doc, docx, ppt, pptx, xls, xlsx, zip, Maxim\u00e1ln\u00ed velikost souboru: 32 MB, Maxim\u00e1ln\u00ed po\u010det soubor\u016f: 10.<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-75185-field_15-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"15\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75185-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_1\">Va\u0161e jm\u00e9no \/ n\u00e1zev firmy<\/label><input type=\"text\" id=\"wpforms-75185-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-75185-field_1-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75185-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-75185-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-75185-field_2-error\" required><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75185-field_3-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_3\">Telefon<\/label><input type=\"tel\" id=\"wpforms-75185-field_3\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][3]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-75185-field_3-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75185-field_14-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-75185-field_14\">PS\u010c <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-75185-field_14\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][14]\" aria-errormessage=\"wpforms-75185-field_14-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-75185-field_16-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"16\"><div id=\"wpforms-75185-field_16\" aria-errormessage=\"wpforms-75185-field_16-error\"><font size=\"2\">Odesl\u00e1n\u00edm popt\u00e1vky souhlas\u00edte se <a href=\"https:\/\/skrivanek.cz\/cz\/zpracovani-ochrana-osobnich-udaju\/\" title=\"Z\u00e1sady zpracov\u00e1n\u00ed osobn\u00edch \u00fadaj\u016f\" target=\"_blank\">z\u00e1sadami zpracov\u00e1n\u00ed osobn\u00edch \u00fadaj\u016f<\/a>.<\/font><\/div><\/div><div id=\"wpforms-75185-field_32-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"32\"><input type=\"hidden\" id=\"wpforms-75185-field_32\" name=\"wpforms[fields][32]\" value=\"[channel]\"><\/div><div id=\"wpforms-75185-field_33-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"33\"><input type=\"hidden\" id=\"wpforms-75185-field_33\" name=\"wpforms[fields][33]\" value=\"[channeldrilldown1]\"><\/div><div id=\"wpforms-75185-field_34-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"34\"><input type=\"hidden\" id=\"wpforms-75185-field_34\" name=\"wpforms[fields][34]\" value=\"[channeldrilldown2]\"><\/div><div id=\"wpforms-75185-field_35-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"35\"><input type=\"hidden\" id=\"wpforms-75185-field_35\" name=\"wpforms[fields][35]\" value=\"[channeldrilldown3]\"><\/div><div id=\"wpforms-75185-field_36-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"36\"><input type=\"hidden\" id=\"wpforms-75185-field_36\" name=\"wpforms[fields][36]\" value=\"[landingpage]\"><\/div><div id=\"wpforms-75185-field_37-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"37\"><input type=\"hidden\" id=\"wpforms-75185-field_37\" name=\"wpforms[fields][37]\" value=\"[landingpagegroup]\"><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-75185-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-75185-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-75185-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"75185\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/12494\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-75185\" class=\"wpforms-submit\" data-alt-text=\"Odes\u00edl\u00e1n\u00ed...\" data-submit-text=\"Odeslat\" aria-live=\"assertive\" value=\"wpforms-submit\">Odeslat<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/skrivanek.cz\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Na\u010d\u00edt\u00e1n\u00ed\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div><div id=\"pgc-12494-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-12494-0-1-0\" class=\"so-panel widget widget_wpa9-editor-ext panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-12494\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2>Kontakt<\/h2>\n<p><strong>Vypl\u0148te kr\u00e1tk\u00fd formul\u00e1\u0159 nebo n\u00e1m napi\u0161te na <a href=\"mailto:s&#107;&#114;iva&#110;&#101;&#107;&#64;s&#107;&#114;&#105;&#118;&#97;n&#101;&#107;&#46;cz?subject=Popt\u00e1v\u00e1m%20jazykov\u00e9%20slu\u017eby&amp;body=V%20z\u00e1jmu%20efektivn\u011bj\u0161\u00ed%20a%20rychlej\u0161\u00ed%20komunikace%20v\u00e1s%20pros\u00edme%20o%20dopln\u011bn\u00ed%20n\u00e1sleduj\u00edc\u00edch%20\u00fadaj\u016f:%0D%0A%0D%0A\u2022 Jm\u00e9no a p\u0159\u00edjmen\u00ed%0D%0A\u2022 Firma%0D%0A\u2022 Telefon%0D%0A\u2022 Typ slu\u017eby%0D%0A\u2022 Jazykov\u00e1 kombinace%0D\">&#115;&#107;&#114;&#105;v&#097;nek&#064;s&#107;r&#105;&#118;an&#101;k&#046;c&#122;<\/a> a&nbsp;my se v\u00e1m brzy ozveme.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div class=\"columns columns-2\" data-columns=\"2\">\n<div class=\"column column-1\">\n<p><img alt=\"csa-20222\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-74210\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2025\/02\/csa-20222.webp\" alt=\"\" width=\"300\" height=\"199\" \/><\/p>\n<\/div>\n<div class=\"column column-2\">\n<p><img alt=\"nimdzi-2024\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-74213\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2025\/02\/nimdzi-2024.webp\" alt=\"\" width=\"300\" height=\"199\" \/><\/p>\n<\/div>\n<\/div>\n<p><img alt=\"iso\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-74225\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2025\/02\/iso.jpg\" alt=\"\" width=\"800\" height=\"400\" \/><\/p>\n<h3>Na\u0161i spokojen\u00ed klienti<\/h3>\n<p>&nbsp;<\/p>\n<div class=\"columns columns-2\" data-columns=\"2\">\n<div class=\"column column-1\">\n<p><img decoding=\"async\" class=\"wp-image-16493 aligncenter\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2022\/04\/ref-abb.svg\" alt=\"abb\" width=\"200\" \/><\/p>\n<\/div>\n<div class=\"column column-2\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-69723\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2024\/04\/alavis-logo-1646502754.jpg\" alt=\"Alavis\" width=\"202\" height=\"74\" \/><\/p>\n<\/div>\n<\/div>\n<div class=\"columns columns-2\" data-columns=\"2\">\n<div class=\"column column-1\">\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11120\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2021\/04\/doosan.svg\" alt=\"doosan\" width=\"200\" \/><\/p>\n<\/div>\n<div class=\"column column-2\">\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11132\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2021\/04\/essox.svg\" alt=\"Reference na p\u0159eklady od ESSOX\" width=\"200\" \/><\/p>\n<\/div>\n<\/div>\n<div class=\"columns columns-2\" data-columns=\"2\">\n<div class=\"column column-1\">\n<p><img decoding=\"async\" class=\"aligncenter wp-image-65027\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2024\/01\/prima.svg\" alt=\"logo prima\" width=\"185\" \/><\/p>\n<\/div>\n<div class=\"column column-2\">\n<p><img alt=\"kosikcz-3\" decoding=\"async\" class=\"aligncenter wp-image-69945\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2024\/05\/kosikcz-3.svg\" alt=\"\" width=\"200\" \/><\/p>\n<\/div>\n<\/div>\n<div class=\"columns columns-2\" data-columns=\"2\">\n<div class=\"column column-1\">\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11106\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2021\/04\/bata.svg\" alt=\"ba\u0165a reference\" width=\"200\" \/><\/p>\n<\/div>\n<div class=\"column column-2\">\n<p><img alt=\"cez-skupina-logo-vertikalni-cz-barva-pozitiv-cmyk-948x520\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-67845\" src=\"https:\/\/skrivanek.cz\/wp-content\/uploads\/2024\/03\/cez-skupina-logo-vertikalni-cz-barva-pozitiv-cmyk-948x520.jpg\" alt=\"\" width=\"200\" height=\"126\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jak v\u00e1m m\u016f\u017eeme pomoci?<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12494","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/12494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/comments?post=12494"}],"version-history":[{"count":4,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/12494\/revisions"}],"predecessor-version":[{"id":79026,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/12494\/revisions\/79026"}],"wp:attachment":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/media?parent=12494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}