{"id":71487,"date":"2024-08-09T09:52:02","date_gmt":"2024-08-09T07:52:02","guid":{"rendered":"https:\/\/skrivanek.cz\/?page_id=71487"},"modified":"2026-03-24T15:10:21","modified_gmt":"2026-03-24T14:10:21","slug":"poptavka-workshop-na-miru","status":"publish","type":"page","link":"https:\/\/skrivanek.cz\/cz\/poptavka-workshop-na-miru\/","title":{"rendered":"Popt\u00e1vka: workshop na m\u00edru"},"content":{"rendered":"<div id=\"pl-71487\"  class=\"panel-layout\" ><div id=\"pg-71487-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-padding-none panel-row-style panel-row-style-for-71487-0\" data-stretch-type=\"full\" ><div id=\"pgc-71487-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-71487-0-0-0\" class=\"so-panel widget widget_wpforms-widget wpforms-widget panel-first-child panel-last-child\" data-index=\"0\" >\r\n<style type=\"text\/css\">\r\n\r\n\r\n\r\nbody #wpforms-75359 {\r\n\t\t\r\n\t\t\tfont-family:inherit;}\r\n\r\n\t\r\n\r\n\tbody #wpforms-75359 .wpforms-head-container {\r\n\t\tborder-width: 0px;}\r\n\r\n\tbody #wpforms-75359 .wpforms-head-container .wpforms-title {\r\n\t\t}\r\n\r\n\tbody #wpforms-75359 .wpforms-head-container .wpforms-description {\r\n\t\t\t\tdisplay:block;\r\n\t}\r\n\r\n\r\n\tbody #wpforms-75359 .wpforms-submit-container .wpforms-submit, body #wpforms-75359 .wpforms-field-pagebreak button.wpforms-page-button {\r\n\t\tcolor:#ffffff ;background-color:#ff643b ;border-width:0px ;border-style:solid ;border-radius:10px ;-web-border-radius:10px ;-moz-border-radius:10px ;\t\t\t}\r\n\r\n\tbody #wpforms-75359 .wpforms-submit-container .wpforms-submit:hover, body #wpforms-75359 .wpforms-field-pagebreak button.wpforms-page-button:hover {\r\n\tbackground-color:;\tcolor:;\t}\r\n\r\n\tbody #wpforms-75359 .wpforms-submit-container,\r\n\tbody #wpforms-75359 .wpforms-field-pagebreak .wpforms-pagebreak-left{\r\n\t\t}\r\n\r\n\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field input[type=text],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field input[type=email],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field input[type=tel],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field input[type=url],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field input[type=password],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field input[type=number]\r\n\t{\r\n\t\tborder-width:1px ;border-style:solid ;\t\t\t}\r\n\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field .wpforms-field-row\r\n\t{\r\n\t\t\t}\r\n\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-layout.wpforms-field input[type=text],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-layout.wpforms-field input[type=email],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-layout.wpforms-field input[type=tel],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-layout.wpforms-field input[type=url],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-layout.wpforms-field input[type=password],\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-layout.wpforms-field input[type=number]{\r\n\t\twidth: 100%;\r\n\t}\r\n\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field .wpforms-field-row input[type=text]{\r\n\t\twidth: 100%;\r\n\t}\r\n\r\n\r\n\r\n\t#wpforms-75359 .wpforms-form .wpforms-field-layout-rows,\r\n\t#wpforms-75359 .wpforms-form .wpforms-field-layout-columns{\r\n\t\t\t}\r\n\r\n\r\n\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field textarea {\r\n\t\t\t\t\tborder-width: 1px;\t}\r\n\r\n \r\n\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field select {\r\n\r\n\t\t\r\n\t\tborder-width: 1px;\t}\r\n\r\n\t\/* dropdown styles on modern background *\/\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-select-style-modern .choices__inner{\r\n\t\t\t\t\r\n\t}\r\n\r\n\t\/* background color on modern dropdown *\/\r\n\t\r\n \r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-radio li label,\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-payment-multiple li label {\r\n\t\t\t}\r\n \r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field-checkbox li label {\r\n\t\t\t}\r\n \r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field .wpforms-field-description {\r\n\r\n\t\t\t}\r\n\r\n \r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field label.wpforms-field-label,\r\n\tbody #wpforms-75359 .wpforms-form .wpforms-field .wpforms-field-label {\r\n\t\tfont-weight: bold;\t}\r\n\r\n\r\n \r\n\tbody #wpforms-confirmation-75359  {\r\n\r\n\t\t\t\tborder-width: 1px;\t}\r\n\r\n\tbody #wpforms-confirmation-75359 p{\r\n\t\ttext-transform: uppercase;\r\n\t\ttext-decoration: underline;\r\n\t\tcolor: inherit;\r\n\t}\r\n\r\n \r\n\tbody #wpforms-75359 label.wpforms-error,\r\n\tbody #wpforms-75359 .wpforms-error[role=\"alert\"] {\r\n\t\t\r\n\t\t\t\tborder-width: 1px;\t}\r\n\/* Styling for Tablets *\/\r\n@media only screen and (max-width: 800px) and (min-width:481px) {\r\n\t\r\n\r\n\r\n\r\n}\r\n\r\n@media only screen and (max-width: 480px){\r\n\t\r\n\r\n\r\n\r\n}\r\n\/*Option to add custom CSS *\/\r\n\r\n\r\n\r\n\t\t<\/style>\r\n\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-75359\"><form id=\"wpforms-form-75359\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"75359\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/cz\/wp-json\/wp\/v2\/pages\/71487\" data-token=\"53c9db360d9af94a5519b395cc7f9f2d\" data-token-time=\"1788368943\"><noscript class=\"wpforms-error-noscript\">Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v&nbsp;prohl\u00ed\u017ee\u010di JavaScript.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v&nbsp;prohl\u00ed\u017ee\u010di JavaScript.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-75359-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-75359-field_4\" >Telefon Va\u0161e Layout<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-75359-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-75359-field_32-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"32\"><fieldset><legend class=\"wpforms-field-label\">Popt\u00e1v\u00e1m <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-75359-field_32\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-75359-field_32_1\" name=\"wpforms[fields][32]\" value=\"jako fyzick\u00e1 osoba\" aria-errormessage=\"wpforms-75359-field_32_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75359-field_32_1\">jako fyzick\u00e1 osoba<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-75359-field_32_2\" name=\"wpforms[fields][32]\" value=\"pro firmu\" aria-errormessage=\"wpforms-75359-field_32_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-75359-field_32_2\">pro firmu<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-75359-field_15-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"15\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75359-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-75359-field_1\">Va\u0161e jm\u00e9no <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-75359-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-75359-field_1-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75359-field_31-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"31\"><label class=\"wpforms-field-label\" for=\"wpforms-75359-field_31\">N\u00e1zev spole\u010dnosti<\/label><input type=\"text\" id=\"wpforms-75359-field_31\" class=\"wpforms-field-medium\" name=\"wpforms[fields][31]\" aria-errormessage=\"wpforms-75359-field_31-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75359-field_3-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-75359-field_3\">Telefon<\/label><input type=\"tel\" id=\"wpforms-75359-field_3\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][3]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-75359-field_3-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-75359-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-75359-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-75359-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-75359-field_2-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-75359-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-75359-field_7\">Jak\u00e9 jsou va\u0161e po\u017eadavky na workshop? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-75359-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-75359-field_7-error\" required><\/textarea><\/div><div id=\"wpforms-75359-field_16-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"16\"><div id=\"wpforms-75359-field_16\" aria-errormessage=\"wpforms-75359-field_16-error\"><font size=\"2\">Odesl\u00e1n\u00edm popt\u00e1vky souhlas\u00edte se <a href=\"https:\/\/skrivanek.cz\/cz\/zpracovani-ochrana-osobnich-udaju\/\" title=\"Z\u00e1sady zpracov\u00e1n\u00ed osobn\u00edch \u00fadaj\u016f\" target=\"_blank\">z\u00e1sadami zpracov\u00e1n\u00ed osobn\u00edch \u00fadaj\u016f<\/a>.<\/font><\/div><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-75359-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-75359-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-75359-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"75359\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/71487\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-75359\" class=\"wpforms-submit\" data-alt-text=\"Odes\u00edl\u00e1n\u00ed...\" data-submit-text=\"Odeslat\" aria-live=\"assertive\" value=\"wpforms-submit\">Odeslat<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/skrivanek.cz\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Na\u010d\u00edt\u00e1n\u00ed\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v&nbsp;prohl\u00ed\u017ee\u010di JavaScript.Chcete-li vyplnit tento formul\u00e1\u0159, pros\u00edm povolte v&nbsp;prohl\u00ed\u017ee\u010di JavaScript. Jak\u00e9 na Layout Popt\u00e1v\u00e1m *jako fyzick\u00e1 osobapro firmuVa\u0161e jm\u00e9no *N\u00e1zev spole\u010dnostiTelefonEmail *Jak\u00e9 jsou va\u0161e po\u017eadavky na workshop? *Odesl\u00e1n\u00edm popt\u00e1vky souhlas\u00edte se z\u00e1sadami zpracov\u00e1n\u00ed osobn\u00edch \u00fadaj\u016f.Odeslat<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-71487","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/71487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/comments?post=71487"}],"version-history":[{"count":3,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/71487\/revisions"}],"predecessor-version":[{"id":80356,"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/pages\/71487\/revisions\/80356"}],"wp:attachment":[{"href":"https:\/\/skrivanek.cz\/cz\/wp-json\/wp\/v2\/media?parent=71487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}